{"id":1837,"date":"2019-03-28T11:04:29","date_gmt":"2019-03-28T10:04:29","guid":{"rendered":"http:\/\/www.masdelabolp.it\/sci-di-fondo\/"},"modified":"2019-12-15T16:19:29","modified_gmt":"2019-12-15T15:19:29","slug":"cross-country-skiing","status":"publish","type":"page","link":"https:\/\/www.masdelabolp.it\/en\/cross-country-skiing\/","title":{"rendered":"Cross-country skiing"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8221;1268&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_3d&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547817466497{margin-top: 50px !important;margin-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2>Cross-country skiing<\/h2>\n<h4>1200km of ski runs in Trentino<\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]Val di Sole offers various cross-country ski centres for a total of about 55 km of slopes, plus 20 km of slopes at the Madonna di Campiglio cross-country ski centre &#8211; Campo Carlo Magno Pass.<\/p>\n<p>Complementary support services are offered, such as waxing rooms, ski rentals, changing rooms, ski schools and specialized instructors.<\/p>\n<p>The SuperNordicSkipass is a quality network of the best cross-country ski centres in Trentino with refreshment and waxing rooms, changing rooms, ski schools and daily maintenance of the ski plan. Access for children up to 10 years old is free of charge.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547817466497{margin-top: 50px !important;margin-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2>Nordic Skiing<\/h2>\n<h4>Cross-country skiing Centres<\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<strong>Cross-country skiing Centre &#8211; RABBI<\/strong><\/p>\n<p>The Rabbi Valley cross-country ski trail develops in the Stelvio National Park along a five-kilometre route, very beautiful both from a technical and naturalistic point of view, maintained both for the skating pass and for the classic one. The ring is divided into several levels of difficulty. The first part of the route takes place on flat ground in the woods. After crossing the Rabbies stream, the most demanding part of the route is tackled, continuing towards the last part of the route among characteristic farmsteads with traditional architecture and then returning to the starting point. Part of the track is illuminated in the long winter evenings to allow cross-country skiing at night! The Venetian Sawmill is very beautiful on the easy part of the route and the Ragaiolo Waterfall is spectacular on the medium difficulty section.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1575455068334{margin-top: 50px !important;margin-bottom: 50px !important;}&#8221;]<strong>TECHNICAL DATA<\/strong><\/p>\n<table class=\"ice\">\n<tbody>\n<tr>\n<td>Km tracks total<\/td>\n<td style=\"text-align: left;\">5<\/td>\n<\/tr>\n<tr>\n<td>Departure altitude<\/td>\n<td style=\"text-align: left;\">1240 meters<\/td>\n<\/tr>\n<tr>\n<td>Height difference<\/td>\n<td style=\"text-align: left;\">35 meters<\/td>\n<\/tr>\n<tr>\n<td>Rings number<\/td>\n<td style=\"text-align: left;\">2<\/td>\n<\/tr>\n<tr>\n<td>Night-time lighting<\/td>\n<td style=\"text-align: left;\">Yes, partial (2,5 km)<\/td>\n<\/tr>\n<tr>\n<td>Tracks Homologation<\/td>\n<td style=\"text-align: left;\">No<\/td>\n<\/tr>\n<tr>\n<td>Restaurant<\/td>\n<td style=\"text-align: left;\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Cross-country skiing school<\/td>\n<td style=\"text-align: left;\">Only during the Christmas period<\/td>\n<\/tr>\n<tr>\n<td>Rental<\/td>\n<td style=\"text-align: left;\">yes<\/td>\n<\/tr>\n<tr>\n<td>Artificial snow<\/td>\n<td style=\"text-align: left;\">Si<\/td>\n<\/tr>\n<tr>\n<td>Service changing rooms<\/td>\n<td style=\"text-align: left;\">No<\/td>\n<\/tr>\n<tr>\n<td>Entry<\/td>\n<td style=\"text-align: left;\">Free<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/vc_column_text][vc_column_text]<strong>Cross-country skiing Centre &#8211; MADONNA DI CAMPIGLIO \u2013 PASSO CAMPO CARLO MAGNO<\/strong><\/p>\n<p>(SuperNordicSkipass)<\/p>\n<p>The Madonna di Campiglio cross-country ski centre, in Pian dei Frari at the Campo Carlo Magno Pass (1660 m), is immersed in the woods of the Adamello Brenta Natural Park. The cross-country skiing centre has comfortable and spacious changing rooms, equipment rental and maintenance, and a skiable floor maintained daily for both skating and classic skiing.<\/p>\n<p>From Passo Campo Carlo Magno there are 22 km of cross-country ski trails, most of which are FISI approved: Campo Scuola Mondifr\u00e0 (0.5 km &#8211; easy), Baby (3.5 km &#8211; easy), Sprint (7.5 km &#8211; medium), World Cup (10.5 km &#8211; difficult).<\/p>\n<p><strong>Cross-country skiing Centre &#8211; VERMIGLIO<\/strong><\/p>\n<p>(SuperNordicSkipass)<\/p>\n<p>The cross-country ski runs of the Vermiglio Cross-country skiing Centre wind for about twenty kilometres in the Volpaia-Stavel-Velon area, in an evocative setting of coniferous woods and characteristic farmsteads. The track includes various levels of difficulty ranging from beginners to competitive preparation.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1548080744417{padding-top: 35px !important;padding-bottom: 35px !important;background-color: #f4f4f4 !important;}&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1575454713264{margin-bottom: 30px !important;}&#8221;]<\/p>\n<h3 class=\"aligncenter\">Discover our special offers<\/h3>\n<p>[\/vc_column_text][vc_column_text]        <div class=\"wcp-carousel-main-wrap\">\n        <section class=\"wcp-slick\"  data-accessibility = on data-autoplay = on data-dots = on data-autoplaySpeed = 3500 data-slidesToShow = 3 data-slidesToShowtab = 2 data-slidesToShowmob = 1 data-speed = 500 data-margin = 20px data-arrows = on id=\"carousel-57\">\n\n                            <div class=\"slick-slide carousel-item-1734\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/una-vacanza-al-maso-bella-e-divertente\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2020\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-53-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2020\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-53-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2020\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-53-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/una-vacanza-al-maso-bella-e-divertente\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Quest'estate vieni a trovarci al Mas de la Bolp, Mountain Chalet! Il nostro Maso in Val di Rabbi -Trentino- \u00e8 situato in posizione aperta e panoramica, al confine fra prato&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/una-vacanza-al-maso-bella-e-divertente\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1746\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/in-trentino-tra-baite-e-rifugi-alpini\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Rifugio-Dorigoni-Val-di-Rabbi-Trentino-1-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Rifugio-Dorigoni-Val-di-Rabbi-Trentino-1-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Rifugio-Dorigoni-Val-di-Rabbi-Trentino-1-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/in-trentino-tra-baite-e-rifugi-alpini\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Una vacanza in Trentino soggiornando tra un rifugio alpino nel Parco Nazionale dello Stelvio ed una baita in Val di Rabbi. Trascorreremo le nostre giornate tra facili passeggiate naturalistiche, ascensioni&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/in-trentino-tra-baite-e-rifugi-alpini\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1739\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/profumi-dautunno-al-mas-de-la-bolp\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Val-di-Rabbi-Trentino-46-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Val-di-Rabbi-Trentino-46-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Val-di-Rabbi-Trentino-46-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/profumi-dautunno-al-mas-de-la-bolp\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            ...anche in Trentino sta arrivando l'autunno con i suoi stupendi colori! Ti proponiamo un soggiorno al Mas de la Bolp (self-catering) incluso di biancheria da letto e bagno, wifi e&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/profumi-dautunno-al-mas-de-la-bolp\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1744\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/il-bramito-del-cervo-nel-parco-nazionale-dello-stelvio\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cervo_Foto-di-Nicola-Angeli_Archivio-PNS-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cervo_Foto-di-Nicola-Angeli_Archivio-PNS-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cervo_Foto-di-Nicola-Angeli_Archivio-PNS-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/il-bramito-del-cervo-nel-parco-nazionale-dello-stelvio\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Un week end d'autunno al Mas de la Bolp per assistere allo splendido rituale del corteggiamento del Cervo in amore nel Parco Nazionale dello Stelvio in Trentino - Val di&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/il-bramito-del-cervo-nel-parco-nazionale-dello-stelvio\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1737\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/la-stua-del-mas-de-la-bolp-e-aperta\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-11-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-11-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-11-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/la-stua-del-mas-de-la-bolp-e-aperta\/\" target=\"_self\" class=\"rpc-title\">\n                La Stua del Mas de la Bolp e\u0300 aperta !            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            \"La Stua\" del Mas de la Bolp, per gruppi o mini-gruppi, \u00e8 aperta ogni sera su prenotazione da ottobre a maggio, per merende dal sapore trentino al rientro dalle vostre&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/la-stua-del-mas-de-la-bolp-e-aperta\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1641\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-freeski-al-mas-de-la-bolp\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-funivia-Pejo-3000-in-inverno-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-funivia-Pejo-3000-in-inverno-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Mas-de-la-Bolp-funivia-Pejo-3000-in-inverno-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-freeski-al-mas-de-la-bolp\/\" target=\"_self\" class=\"rpc-title\">\n                Speciale FreeSki al Mas de la Bolp!            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Richiedi le nostre settimane promozionali con skipass incluso per il prossimo inverno 2024 - 2025! La promozione include soggiorno al Mas de la Bolp (self-catering) incluso biancheria da letto e&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-freeski-al-mas-de-la-bolp\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1731\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-iceclimber\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cascate-di-Valorzi-Mas-de-la-Bolp-Val-di-Rabbi-Trentino-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cascate-di-Valorzi-Mas-de-la-Bolp-Val-di-Rabbi-Trentino-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/Cascate-di-Valorzi-Mas-de-la-Bolp-Val-di-Rabbi-Trentino-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-iceclimber\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Il Mas de la Bolp e\u0300 sotto l\u2019anfiteatro delle cascate di Valorz. Avvicinamento 20 minuti a piedi! Soggiorno al Mas de la Bolp (self-catering) incluso biancheria da letto e bagno,&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/speciale-iceclimber\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1749\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/primavera-in-alta-quota-sci-autentico-per-tracce-eleganti-ed-effimere\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-chalet-Val-di-Rabbi-Trentino-5-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-chalet-Val-di-Rabbi-Trentino-5-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-chalet-Val-di-Rabbi-Trentino-5-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/primavera-in-alta-quota-sci-autentico-per-tracce-eleganti-ed-effimere\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Alcuni giorni al Mas de la Bolp, in Trentino, per scoprire il mondo meraviglioso delle alte quote primaverili! Neve trasformata, giornate lunghe e temperature non troppo rigide per due fantastiche&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/primavera-in-alta-quota-sci-autentico-per-tracce-eleganti-ed-effimere\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1747\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/spring-weekend-at-mas-de-la-bolp\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-30-1-600x410.jpg\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-30-1-600x410.jpg 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/01\/Mas-de-la-Bolp-Mountain-Chalet-Val-di-Rabbi-Trentino-30-1-800x547.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/spring-weekend-at-mas-de-la-bolp\/\" target=\"_self\" class=\"rpc-title\">\n                Week end di primavera al Maso!            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            A weekend at Mas de la Bolp to experience the environments, colours and flavours of the Stelvio National Park in Trentino! Our farm in Val di Rabbi -Trentino- is situated&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/spring-weekend-at-mas-de-la-bolp\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                            <div class=\"slick-slide carousel-item-1741\">\n                    <div class=\"post-style-2 rpc-bg rpc-box\">\n    <div class=\"wcp-img-wrap\">\n        <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/pomaria-in-trentino-per-la-festa-del-raccolto\/\">\n            <div class=\"fixed-height-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"410\" src=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/pomaria-600x410.png\" class=\"attachment-600x410 size-600x410 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/pomaria-600x410.png 600w, https:\/\/www.masdelabolp.it\/wp-content\/uploads\/2019\/04\/pomaria-800x547.png 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>        <\/a>\n    <\/div>\n    <div class=\"wcp-content-wrap\">\n        <h3>\n            <a class=\"rpc-title\" href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/pomaria-in-trentino-per-la-festa-del-raccolto\/\" target=\"_self\" class=\"rpc-title\">\n                            <\/a>\n        <\/h3>\n                <div class=\"wcp-post-contents rpc-content\">\n\n            Un week end d'autunno al Mas de la Bolp per assistere ad una grande manifestazione all\u2019insegna dell\u2019arte, della cultura, della gastronomia, della musica e della tradizione. Un evento alla scoperta&hellip;\n                            <br>\n                <a href=\"https:\/\/www.masdelabolp.it\/en\/offerte\/pomaria-in-trentino-per-la-festa-del-raccolto\/\" target=\"_self\" class=\"\">Scopri l'offerta \u00bb<\/a>\n        \n        <\/div>        \n    <\/div>\n<\/div>                <\/div>    \n\n                \n        <\/section>\n        <\/div>\n        <style>#carousel-57 .slick-prev:before, #carousel-57 .slick-next:before { color: #ffffff !important;}#carousel-57 .slick-slide { margin: 2px 20px; } #carousel-57 .rpc-title { color: ; } #carousel-57 .rpc-content { color: ; } #carousel-57 .rpc-date { background-color: ; } #carousel-57 .rpc-date { color: ; } #carousel-57 .rpc-overlay { background-color: ; } #carousel-57 .carousel-style9 { border-top-color: ; } #carousel-57 .carousel-style9 .button:before { background-color: ; } #carousel-57 .rpc-box { box-shadow: ; } #carousel-57 .rpc-bg { background-color: ; } #carousel-57 .rpc-title-bg { background-color: ; } #carousel-57 .rpc-box { border: 1px solid #e2e2e2; } #carousel-57 .fixed-height-image { height: ; } #carousel-57 .style4 { padding: 10px; } #carousel-57 .style6 { padding: 10px; } #carousel-57 .slick-next:before { content: '\\ \\f152 '; } #carousel-57 .slick-prev:before { content: '\\ \\f191'; }#carousel-57 .slick-next:before, #carousel-57 .slick-prev:before { background-color: #9d2a26; padding: 5px; } #carousel-57 .rpc-title { font-family: EB Garamond; } #carousel-57 .rpc-title { font-size: 24px; } #carousel-57 .rpc-content { font-family: Muli; } #carousel-57 .rpc-content { font-size: 15px; } <\/style>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=&#8221;1268&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_3d&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1547817466497{margin-top: 50px !important;margin-bottom: 50px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_column_text] Cross-country skiing 1200km of ski runs in Trentino [\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]Val di Sole offers various cross-country ski centres for a total of about 55 km of slopes, plus 20 km of slopes at the Madonna di Campiglio cross-country ski centre &#8211; Campo Carlo Magno Pass.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"Cross-country skiing\r\nVAL DI RABBI, PASSO CAMPO CARLO MAGNO, MADONNA DI CAMPIGLIO","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-1837","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/pages\/1837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":7,"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/pages\/1837\/revisions"}],"predecessor-version":[{"id":1847,"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/pages\/1837\/revisions\/1847"}],"wp:attachment":[{"href":"https:\/\/www.masdelabolp.it\/en\/wp-json\/wp\/v2\/media?parent=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}